{"id":13687,"date":"2021-04-28T10:55:21","date_gmt":"2021-04-28T07:55:21","guid":{"rendered":"https:\/\/biobeach.gr\/web-check-in\/"},"modified":"2021-05-10T08:55:51","modified_gmt":"2021-05-10T05:55:51","slug":"web-check-in","status":"publish","type":"page","link":"https:\/\/biobeach.gr\/de\/web-check-in\/","title":{"rendered":"Web Check-In"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13687\" class=\"elementor elementor-13687 elementor-13675\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d981fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d981fa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e3402a6\" data-id=\"e3402a6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b7393e elementor-widget elementor-widget-text-editor\" data-id=\"9b7393e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t\t<script type=\"text\/javascript\">var gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,initializeOnLoaded:function(o){gform.domLoaded&&gform.scriptsLoaded?o():!gform.domLoaded&&gform.scriptsLoaded?window.addEventListener(\"DOMContentLoaded\",o):document.addEventListener(\"gform_main_scripts_loaded\",o)},hooks:{action:{},filter:{}},addAction:function(o,n,r,t){gform.addHook(\"action\",o,n,r,t)},addFilter:function(o,n,r,t){gform.addHook(\"filter\",o,n,r,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,n){gform.removeHook(\"action\",o,n)},removeFilter:function(o,n,r){gform.removeHook(\"filter\",o,n,r)},addHook:function(o,n,r,t,i){null==gform.hooks[o][n]&&(gform.hooks[o][n]=[]);var e=gform.hooks[o][n];null==i&&(i=n+\"_\"+e.length),gform.hooks[o][n].push({tag:i,callable:r,priority:t=null==t?10:t})},doHook:function(n,o,r){var t;if(r=Array.prototype.slice.call(r,1),null!=gform.hooks[n][o]&&((o=gform.hooks[n][o]).sort(function(o,n){return o.priority-n.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==n?t.apply(null,r):r[0]=t.apply(null,r)})),\"filter\"==n)return r[0]},removeHook:function(o,n,t,i){var r;null!=gform.hooks[o][n]&&(r=(r=gform.hooks[o][n]).filter(function(o,n,r){return!!(null!=i&&i!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][n]=r)}});<\/script>\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_5' ><div id='gf_5' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_5' id='gform_5'  action='\/de\/wp-json\/wp\/v2\/pages\/13687#gf_5' data-formid='5' >\n                        <div class='gform-body gform_body'><ul id='gform_fields_5' class='gform_fields top_label form_sublabel_above description_above'><li id=\"field_5_1\"  class=\"gfield gfield--type-date gfield--input-type-datepicker gfield--datepicker-default-icon gf_left_half gfield_contains_required field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_1\"><label class='gfield_label gform-field-label' for='input_5_1' >Ankunftstag<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_date'>\n                            <input name='input_1' id='input_5_1' type='text' value='' class='datepicker gform-datepicker dmy datepicker_with_icon gdatepicker_with_icon'   placeholder='dd\/mm\/yyyy' aria-describedby=\"input_5_1_date_format\" aria-invalid=\"false\" aria-required=\"true\"\/>\n                            <span id='input_5_1_date_format' class='screen-reader-text'>TT Schr\u00e4gstrich MM Schr\u00e4gstrich JJJJ<\/span>\n                        <\/div>\n                        <input type='hidden' id='gforms_calendar_icon_input_5_1' class='gform_hidden' value='https:\/\/biobeach.gr\/wp-content\/plugins\/gravityforms\/images\/datepicker\/datepicker.svg'\/><\/li><li id=\"field_5_3\"  class=\"gfield gfield--type-date gfield--input-type-datepicker gfield--datepicker-default-icon gf_right_half gfield_contains_required field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_3\"><label class='gfield_label gform-field-label' for='input_5_3' >Abreisetag<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_date'>\n                            <input name='input_3' id='input_5_3' type='text' value='' class='datepicker gform-datepicker dmy datepicker_with_icon gdatepicker_with_icon'   placeholder='dd\/mm\/yyyy' aria-describedby=\"input_5_3_date_format\" aria-invalid=\"false\" aria-required=\"true\"\/>\n                            <span id='input_5_3_date_format' class='screen-reader-text'>TT Schr\u00e4gstrich MM Schr\u00e4gstrich JJJJ<\/span>\n                        <\/div>\n                        <input type='hidden' id='gforms_calendar_icon_input_5_3' class='gform_hidden' value='https:\/\/biobeach.gr\/wp-content\/plugins\/gravityforms\/images\/datepicker\/datepicker.svg'\/><\/li><li id=\"field_5_11\"  class=\"gfield gfield--type-section gsection field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_11\"><h2 class=\"gsection_title\">Pers\u00f6nliche Information<\/h2><\/li><li id=\"field_5_4\"  class=\"gfield gfield--type-name gfield_contains_required field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_4\"><label class='gfield_label gform-field-label gfield_label_before_complex'  >Name<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_5_4'>\n                            \n                            <span id='input_5_4_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <label for='input_5_4_3' class='gform-field-label gform-field-label--type-sub '>Vorname<\/label>\n                                                    <input type='text' name='input_4.3' id='input_5_4_3' value=''   aria-required='true'     \/>\n                                                <\/span>\n                            \n                            <span id='input_5_4_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                            <label for='input_5_4_6' class='gform-field-label gform-field-label--type-sub '>Nachname<\/label>\n                                                            <input type='text' name='input_4.6' id='input_5_4_6' value=''   aria-required='true'     \/>\n                                                        <\/span>\n                            \n                        <\/div><\/li><li id=\"field_5_5\"  class=\"gfield gfield--type-date gfield--input-type-datepicker gfield--datepicker-default-icon gf_left_half gfield_contains_required field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_5\"><label class='gfield_label gform-field-label' for='input_5_5' >Geburtsdatum<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_date'>\n                            <input name='input_5' id='input_5_5' type='text' value='' class='datepicker gform-datepicker dmy datepicker_with_icon gdatepicker_with_icon'   placeholder='dd\/mm\/yyyy' aria-describedby=\"input_5_5_date_format\" aria-invalid=\"false\" aria-required=\"true\"\/>\n                            <span id='input_5_5_date_format' class='screen-reader-text'>TT Schr\u00e4gstrich MM Schr\u00e4gstrich JJJJ<\/span>\n                        <\/div>\n                        <input type='hidden' id='gforms_calendar_icon_input_5_5' class='gform_hidden' value='https:\/\/biobeach.gr\/wp-content\/plugins\/gravityforms\/images\/datepicker\/datepicker.svg'\/><\/li><li id=\"field_5_6\"  class=\"gfield gfield--type-text gf_right_half gfield_contains_required field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_6\"><label class='gfield_label gform-field-label' for='input_5_6' >Nationalit\u00e4t<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_6' id='input_5_6' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/> <\/div><\/li><li id=\"field_5_7\"  class=\"gfield gfield--type-email gf_left_half gfield_contains_required field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_7\"><label class='gfield_label gform-field-label' for='input_5_7' >Email<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_7' id='input_5_7' type='text' value='' class='medium'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_5_8\"  class=\"gfield gfield--type-phone gf_right_half gfield_contains_required field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_8\"><label class='gfield_label gform-field-label' for='input_5_8' >Telefonnummer<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_phone'><input name='input_8' id='input_5_8' type='text' value='' class='medium'   aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_5_10\"  class=\"gfield gfield--type-text gfield_contains_required field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_10\"><label class='gfield_label gform-field-label' for='input_5_10' >Pass- oder Personalausweisnummer<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_10' id='input_5_10' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/> <\/div><\/li><li id=\"field_5_12\"  class=\"gfield gfield--type-section gsection field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_12\"><h2 class=\"gsection_title\">Mitreisenden<\/h2><\/li><li id=\"field_5_16\"  class=\"gfield gfield--type-section gsection webcheckin-person-section field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_16\"><h2 class=\"gsection_title\">Person 1<\/h2><\/li><li id=\"field_5_13\"  class=\"gfield gfield--type-name field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_13\"><label class='gfield_label gform-field-label gfield_label_before_complex'  >Name<\/label><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_5_13'>\n                            \n                            <span id='input_5_13_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <label for='input_5_13_3' class='gform-field-label gform-field-label--type-sub '>Vorname<\/label>\n                                                    <input type='text' name='input_13.3' id='input_5_13_3' value=''   aria-required='false'     \/>\n                                                <\/span>\n                            \n                            <span id='input_5_13_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                            <label for='input_5_13_6' class='gform-field-label gform-field-label--type-sub '>Nachname<\/label>\n                                                            <input type='text' name='input_13.6' id='input_5_13_6' value=''   aria-required='false'     \/>\n                                                        <\/span>\n                            \n                        <\/div><\/li><li id=\"field_5_24\"  class=\"gfield gfield--type-date gfield--input-type-datepicker gfield--datepicker-no-icon gf_left_half field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_24\"><label class='gfield_label gform-field-label' for='input_5_24' >Geburtsdatum<\/label><div class='ginput_container ginput_container_date'>\n                            <input name='input_24' id='input_5_24' type='text' value='' class='datepicker gform-datepicker dmy datepicker_no_icon gdatepicker-no-icon'   placeholder='dd\/mm\/yyyy' aria-describedby=\"input_5_24_date_format\" aria-invalid=\"false\" \/>\n                            <span id='input_5_24_date_format' class='screen-reader-text'>TT Schr\u00e4gstrich MM Schr\u00e4gstrich JJJJ<\/span>\n                        <\/div>\n                        <input type='hidden' id='gforms_calendar_icon_input_5_24' class='gform_hidden' value='https:\/\/biobeach.gr\/wp-content\/plugins\/gravityforms\/images\/datepicker\/datepicker.svg'\/><\/li><li id=\"field_5_15\"  class=\"gfield gfield--type-text gf_right_half field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_15\"><label class='gfield_label gform-field-label' for='input_5_15' >Pass- oder Personalausweisnummer<\/label><div class='ginput_container ginput_container_text'><input name='input_15' id='input_5_15' type='text' value='' class='medium'      aria-invalid=\"false\"   \/> <\/div><\/li><li id=\"field_5_17\"  class=\"gfield gfield--type-section gsection webcheckin-person-section field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_17\"><h2 class=\"gsection_title\">Person 2<\/h2><\/li><li id=\"field_5_20\"  class=\"gfield gfield--type-name field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_20\"><label class='gfield_label gform-field-label gfield_label_before_complex'  >Name<\/label><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_5_20'>\n                            \n                            <span id='input_5_20_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <label for='input_5_20_3' class='gform-field-label gform-field-label--type-sub '>Vorname<\/label>\n                                                    <input type='text' name='input_20.3' id='input_5_20_3' value=''   aria-required='false'     \/>\n                                                <\/span>\n                            \n                            <span id='input_5_20_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                            <label for='input_5_20_6' class='gform-field-label gform-field-label--type-sub '>Nachname<\/label>\n                                                            <input type='text' name='input_20.6' id='input_5_20_6' value=''   aria-required='false'     \/>\n                                                        <\/span>\n                            \n                        <\/div><\/li><li id=\"field_5_23\"  class=\"gfield gfield--type-date gfield--input-type-datepicker gfield--datepicker-no-icon gf_left_half field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_23\"><label class='gfield_label gform-field-label' for='input_5_23' >Geburtsdatum<\/label><div class='ginput_container ginput_container_date'>\n                            <input name='input_23' id='input_5_23' type='text' value='' class='datepicker gform-datepicker dmy datepicker_no_icon gdatepicker-no-icon'   placeholder='dd\/mm\/yyyy' aria-describedby=\"input_5_23_date_format\" aria-invalid=\"false\" \/>\n                            <span id='input_5_23_date_format' class='screen-reader-text'>TT Schr\u00e4gstrich MM Schr\u00e4gstrich JJJJ<\/span>\n                        <\/div>\n                        <input type='hidden' id='gforms_calendar_icon_input_5_23' class='gform_hidden' value='https:\/\/biobeach.gr\/wp-content\/plugins\/gravityforms\/images\/datepicker\/datepicker.svg'\/><\/li><li id=\"field_5_29\"  class=\"gfield gfield--type-text gf_right_half field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_29\"><label class='gfield_label gform-field-label' for='input_5_29' >Pass- oder Personalausweisnummer<\/label><div class='ginput_container ginput_container_text'><input name='input_29' id='input_5_29' type='text' value='' class='medium'      aria-invalid=\"false\"   \/> <\/div><\/li><li id=\"field_5_19\"  class=\"gfield gfield--type-section gsection webcheckin-person-section field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_19\"><h2 class=\"gsection_title\">Person 3<\/h2><\/li><li id=\"field_5_21\"  class=\"gfield gfield--type-name field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_21\"><label class='gfield_label gform-field-label gfield_label_before_complex'  >Name<\/label><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_5_21'>\n                            \n                            <span id='input_5_21_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <label for='input_5_21_3' class='gform-field-label gform-field-label--type-sub '>Vorname<\/label>\n                                                    <input type='text' name='input_21.3' id='input_5_21_3' value=''   aria-required='false'     \/>\n                                                <\/span>\n                            \n                            <span id='input_5_21_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                            <label for='input_5_21_6' class='gform-field-label gform-field-label--type-sub '>Nachname<\/label>\n                                                            <input type='text' name='input_21.6' id='input_5_21_6' value=''   aria-required='false'     \/>\n                                                        <\/span>\n                            \n                        <\/div><\/li><li id=\"field_5_14\"  class=\"gfield gfield--type-date gfield--input-type-datepicker gfield--datepicker-no-icon gf_left_half field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_14\"><label class='gfield_label gform-field-label' for='input_5_14' >Geburtsdatum<\/label><div class='ginput_container ginput_container_date'>\n                            <input name='input_14' id='input_5_14' type='text' value='' class='datepicker gform-datepicker dmy datepicker_no_icon gdatepicker-no-icon'   placeholder='dd\/mm\/yyyy' aria-describedby=\"input_5_14_date_format\" aria-invalid=\"false\" \/>\n                            <span id='input_5_14_date_format' class='screen-reader-text'>TT Schr\u00e4gstrich MM Schr\u00e4gstrich JJJJ<\/span>\n                        <\/div>\n                        <input type='hidden' id='gforms_calendar_icon_input_5_14' class='gform_hidden' value='https:\/\/biobeach.gr\/wp-content\/plugins\/gravityforms\/images\/datepicker\/datepicker.svg'\/><\/li><li id=\"field_5_28\"  class=\"gfield gfield--type-text gf_right_half field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_28\"><label class='gfield_label gform-field-label' for='input_5_28' >Pass- oder Personalausweisnummer<\/label><div class='ginput_container ginput_container_text'><input name='input_28' id='input_5_28' type='text' value='' class='medium'      aria-invalid=\"false\"   \/> <\/div><\/li><li id=\"field_5_18\"  class=\"gfield gfield--type-section gsection webcheckin-person-section field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_18\"><h2 class=\"gsection_title\">Person 4<\/h2><\/li><li id=\"field_5_22\"  class=\"gfield gfield--type-name field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_22\"><label class='gfield_label gform-field-label gfield_label_before_complex'  >Name<\/label><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_5_22'>\n                            \n                            <span id='input_5_22_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <label for='input_5_22_3' class='gform-field-label gform-field-label--type-sub '>Vorname<\/label>\n                                                    <input type='text' name='input_22.3' id='input_5_22_3' value=''   aria-required='false'     \/>\n                                                <\/span>\n                            \n                            <span id='input_5_22_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                            <label for='input_5_22_6' class='gform-field-label gform-field-label--type-sub '>Nachname<\/label>\n                                                            <input type='text' name='input_22.6' id='input_5_22_6' value=''   aria-required='false'     \/>\n                                                        <\/span>\n                            \n                        <\/div><\/li><li id=\"field_5_25\"  class=\"gfield gfield--type-date gfield--input-type-datepicker gfield--datepicker-no-icon gf_left_half field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_25\"><label class='gfield_label gform-field-label' for='input_5_25' >Geburtsdatum<\/label><div class='ginput_container ginput_container_date'>\n                            <input name='input_25' id='input_5_25' type='text' value='' class='datepicker gform-datepicker dmy datepicker_no_icon gdatepicker-no-icon'   placeholder='dd\/mm\/yyyy' aria-describedby=\"input_5_25_date_format\" aria-invalid=\"false\" \/>\n                            <span id='input_5_25_date_format' class='screen-reader-text'>TT Schr\u00e4gstrich MM Schr\u00e4gstrich JJJJ<\/span>\n                        <\/div>\n                        <input type='hidden' id='gforms_calendar_icon_input_5_25' class='gform_hidden' value='https:\/\/biobeach.gr\/wp-content\/plugins\/gravityforms\/images\/datepicker\/datepicker.svg'\/><\/li><li id=\"field_5_27\"  class=\"gfield gfield--type-text gf_right_half field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_27\"><label class='gfield_label gform-field-label' for='input_5_27' >Pass- oder Personalausweisnummer<\/label><div class='ginput_container ginput_container_text'><input name='input_27' id='input_5_27' type='text' value='' class='medium'      aria-invalid=\"false\"   \/> <\/div><\/li><li id=\"field_5_31\"  class=\"gfield gfield--type-section gsection field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_31\"><h2 class=\"gsection_title\"><\/h2><\/li><li id=\"field_5_30\"  class=\"gfield gfield--type-select field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_30\"><label class='gfield_label gform-field-label' for='input_5_30' >Haben Sie schon einmal unser Hotel besucht? Wenn ja, Ihr wievielter Mal ist es?<\/label><div class='ginput_container ginput_container_select'><select name='input_30' id='input_5_30' class='medium gfield_select'     aria-invalid=\"false\" ><option value='First time' selected='selected'>First time<\/option><option value='1' >1<\/option><option value='2' >2<\/option><option value='3' >3<\/option><option value='4' >4<\/option><option value='5' >5<\/option><option value='6+' >6+<\/option><\/select><\/div><\/li><li id=\"field_5_32\"  class=\"gfield gfield--type-textarea field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_32\"><label class='gfield_label gform-field-label' for='input_5_32' >Bitte nennen Sie alle Lebensmittel, gegen die Sie allergisch sind<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_32' id='input_5_32' class='textarea medium'      aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/li><li id=\"field_5_33\"  class=\"gfield gfield--type-consent gfield--type-choice gfield--input-type-consent field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_33\"><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex'  ><\/label><div class='ginput_container ginput_container_consent'><input name='input_33.1' id='input_5_33_1' type='checkbox' value='1'    aria-invalid=\"false\"   \/> <label class=\"gform-field-label gform-field-label--type-inline gfield_consent_label\" for='input_5_33_1' >Ich bin damit einverstanden, die oben genannten Daten f\u00fcr Angebote und Newsletter von BIO BEACH HOTEL zu verwenden<\/label><input type='hidden' name='input_33.2' value='Ich bin damit einverstanden, die oben genannten Daten f\u00fcr Angebote und Newsletter von BIO BEACH HOTEL zu verwenden' class='gform_hidden' \/><input type='hidden' name='input_33.3' value='4' class='gform_hidden' \/><\/div><\/li><li id=\"field_5_35\"  class=\"gfield gfield--type-consent gfield--type-choice gfield--input-type-consent field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_35\"><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex'  ><\/label><div class='ginput_container ginput_container_consent'><input name='input_35.1' id='input_5_35_1' type='checkbox' value='1'    aria-invalid=\"false\"   \/> <label class=\"gform-field-label gform-field-label--type-inline gfield_consent_label\" for='input_5_35_1' >Ich bin damit einverstanden, die oben genannten Daten f\u00fcr die Ver\u00f6ffentlichung von Fotos \/ Videos auf den Sozial-Media-Seiten unseres Unternehmens (Facebook, Instagram) zu verwenden.<\/label><input type='hidden' name='input_35.2' value='Ich bin damit einverstanden, die oben genannten Daten f\u00fcr die Ver\u00f6ffentlichung von Fotos \/ Videos auf den Sozial-Media-Seiten unseres Unternehmens (Facebook, Instagram) zu verwenden.' class='gform_hidden' \/><input type='hidden' name='input_35.3' value='4' class='gform_hidden' \/><\/div><\/li><li id=\"field_5_36\"  class=\"gfield gfield--type-consent gfield--type-choice gfield--input-type-consent field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_36\"><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex'  ><\/label><div class='ginput_container ginput_container_consent'><input name='input_36.1' id='input_5_36_1' type='checkbox' value='1'    aria-invalid=\"false\"   \/> <label class=\"gform-field-label gform-field-label--type-inline gfield_consent_label\" for='input_5_36_1' >Ich bin damit einverstanden, die oben genannten Daten f\u00fcr einen besseren Service w\u00e4hrend meines Aufenthalts oder bei einer zuk\u00fcnftigen Reservierung (Geburtstage, wiederkehrende Kunden, Jahrestage usw.) zu verwenden.<\/label><input type='hidden' name='input_36.2' value='Ich bin damit einverstanden, die oben genannten Daten f\u00fcr einen besseren Service w\u00e4hrend meines Aufenthalts oder bei einer zuk\u00fcnftigen Reservierung (Geburtstage, wiederkehrende Kunden, Jahrestage usw.) zu verwenden.' class='gform_hidden' \/><input type='hidden' name='input_36.3' value='4' class='gform_hidden' \/><\/div><\/li><li id=\"field_5_37\"  class=\"gfield gfield--type-consent gfield--type-choice gfield--input-type-consent field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_37\"><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex'  ><\/label><div class='ginput_container ginput_container_consent'><input name='input_37.1' id='input_5_37_1' type='checkbox' value='1'    aria-invalid=\"false\"   \/> <label class=\"gform-field-label gform-field-label--type-inline gfield_consent_label\" for='input_5_37_1' >Ich bin damit einverstanden, die oben genannten Daten f\u00fcr personalisierte drahtlose Internetzugangsdienste zu verwenden<\/label><input type='hidden' name='input_37.2' value='Ich bin damit einverstanden, die oben genannten Daten f\u00fcr personalisierte drahtlose Internetzugangsdienste zu verwenden' class='gform_hidden' \/><input type='hidden' name='input_37.3' value='4' class='gform_hidden' \/><\/div><\/li><li id=\"field_5_38\"  class=\"gfield gfield--type-consent gfield--type-choice gfield--input-type-consent field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_38\"><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex'  ><\/label><div class='ginput_container ginput_container_consent'><input name='input_38.1' id='input_5_38_1' type='checkbox' value='1'    aria-invalid=\"false\"   \/> <label class=\"gform-field-label gform-field-label--type-inline gfield_consent_label\" for='input_5_38_1' >Ich bin damit einverstanden, meine Unterkunft am Abreisetag um 12.00 Uhr freizugeben<\/label><input type='hidden' name='input_38.2' value='Ich bin damit einverstanden, meine Unterkunft am Abreisetag um 12.00 Uhr freizugeben' class='gform_hidden' \/><input type='hidden' name='input_38.3' value='4' class='gform_hidden' \/><\/div><\/li><li id=\"field_5_44\"  class=\"gfield gfield--type-consent gfield--type-choice gfield--input-type-consent field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_44\"><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex'  ><\/label><div class='ginput_container ginput_container_consent'><input name='input_44.1' id='input_5_44_1' type='checkbox' value='1'    aria-invalid=\"false\"   \/> <label class=\"gform-field-label gform-field-label--type-inline gfield_consent_label\" for='input_5_44_1' >Ich akzeptiere die Verwendung der oben genannten Daten zum Schutz der \u00f6ffentlichen Gesundheit.<\/label><input type='hidden' name='input_44.2' value='Ich akzeptiere die Verwendung der oben genannten Daten zum Schutz der \u00f6ffentlichen Gesundheit.' class='gform_hidden' \/><input type='hidden' name='input_44.3' value='4' class='gform_hidden' \/><\/div><\/li><li id=\"field_5_41\"  class=\"gfield gfield--type-html webcheckin_html gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_41\"><p>Die Gesch\u00e4ftsf\u00fchrung \u00fcbernimmt keine Verantwortung f\u00fcr Wertsachen, die im G\u00e4stezimmer zur\u00fcckgelassen werden. Ein Safe ist im Zimmer gegen Aufpreis vorhanden.<\/p><\/li><li id=\"field_5_43\"  class=\"gfield gfield--type-html webcheckin_scripts gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_43\">\n<script type=\"text\/javascript\">\n\/**\n * Gravity Wiz \/\/ Gravity Forms \/\/ Disable Submission when Pressing Enter \n * http:\/\/gravitywiz.com\/disable-submission-when-pressing-enter-for-gravity-forms\/\n *\/\njQuery(document).on( 'keypress', '.gform_wrapper', function (e) {\n    var code = e.keyCode || e.which;\n    if ( code == 13 && ! jQuery( e.target ).is( 'textarea,input[type=\"submit\"],input[type=\"button\"]' ) ) {\n        e.preventDefault();\n        return false;\n    }\n} );\n<\/script><\/li><li id=\"field_5_42\"  class=\"gfield gfield--type-html webcheckin_style gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_42\"><style>\n.ui-datepicker{\n    font-size: 16px;\n}\n\n.ui-datepicker select.ui-datepicker-month, \n.ui-datepicker select.ui-datepicker-year{\n    width: 100%;\n}\n\n.gsection{\n    background-color: #EAEAEA;\n    margin: 32px 0 0 0 !important;\n    padding: 10px 6px 8px 6px !important;\n}\n\nlabel.gfield_consent_label{\n    display: inline;\n}\n\n.gform_body input[type='checkbox']{\n    width: 20px;\n    height:20px;\n}\n\n.gfield_html{\n    margin-top: 40px !important;\n    padding: 10px !important;\n    background-color: #EAEAEA;\n    font-style: italic;\n}\n\n.webcheckin_style,\n.webcheckin_scripts,\n.webcheckin_captcha{\n    display: none;\n}\n\n<\/style><\/li><li id=\"field_5_34\"  class=\"gfield gfield--type-captcha webcheckin_captcha field_sublabel_above gfield--no-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_34\"><label class='gfield_label gform-field-label screen-reader-text' for='input_5_34' ><\/label><div id='input_5_34' class='ginput_container ginput_recaptcha' data-sitekey='6LdjsrsaAAAAAP9w6evU_RjiXYLKlq67WpW9iHNT'  data-theme='light' data-tabindex='-1' data-size='invisible' data-badge='bottomright'><\/div><\/li><li id=\"field_5_45\"  class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_above gfield--has-description field_description_above gfield_visibility_visible\"  data-js-reload=\"field_5_45\"><label class='gfield_label gform-field-label' for='input_5_45' >Comments<\/label><div class='gfield_description' id='gfield_description_5_45'>Dieses Feld dient zur Validierung und sollte nicht ver\u00e4ndert werden.<\/div><div class='ginput_container'><input name='input_45' id='input_5_45' type='text' value='' \/><\/div><\/li><\/ul><\/div>\n        <div class='gform_footer top_label'> <input type='submit' id='gform_submit_button_5' class='gform_button button' value='Submit'  onclick='if(window[\"gf_submitting_5\"]){return false;}  window[\"gf_submitting_5\"]=true;  ' onkeypress='if( event.keyCode == 13 ){ if(window[\"gf_submitting_5\"]){return false;} window[\"gf_submitting_5\"]=true;  jQuery(\"#gform_5\").trigger(\"submit\",[true]); }' \/> <input type='hidden' name='gform_ajax' value='form_id=5&amp;title=&amp;description=&amp;tabindex=0&amp;theme=data-form-theme=&#039;legacy&#039;' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_5' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='5' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_5' value='WyJ7XCIzMy4xXCI6XCJjZDMwMzUyN2Q1NTlmYjMwZjQ4NTNlMDI1YTJkZTQ3N1wiLFwiMzMuMlwiOlwiM2FlYTc1Nzc1MjZmODQyODMzNTljOGI1Y2RiMWYxYzFcIixcIjMzLjNcIjpcImM4NjQ4OTQxNzQ0ZGY5OWYxMWE2YzlkMGJkOTFmNDVhXCIsXCIzNS4xXCI6XCJjZDMwMzUyN2Q1NTlmYjMwZjQ4NTNlMDI1YTJkZTQ3N1wiLFwiMzUuMlwiOlwiZDllZWE0NGU5MGE2M2I1MTNkNjY2NTgwNWUyYzI3ODRcIixcIjM1LjNcIjpcImM4NjQ4OTQxNzQ0ZGY5OWYxMWE2YzlkMGJkOTFmNDVhXCIsXCIzNi4xXCI6XCJjZDMwMzUyN2Q1NTlmYjMwZjQ4NTNlMDI1YTJkZTQ3N1wiLFwiMzYuMlwiOlwiOWI1ZDE2MDllZjlmZjMzNDAzY2ZjYWRmMmVlNWFkYWRcIixcIjM2LjNcIjpcImM4NjQ4OTQxNzQ0ZGY5OWYxMWE2YzlkMGJkOTFmNDVhXCIsXCIzNy4xXCI6XCJjZDMwMzUyN2Q1NTlmYjMwZjQ4NTNlMDI1YTJkZTQ3N1wiLFwiMzcuMlwiOlwiMGZkZjNhNDgzNmQxOGRhMjFlZGY3MTZhMWQ5ZWM2YzNcIixcIjM3LjNcIjpcImM4NjQ4OTQxNzQ0ZGY5OWYxMWE2YzlkMGJkOTFmNDVhXCIsXCIzOC4xXCI6XCJjZDMwMzUyN2Q1NTlmYjMwZjQ4NTNlMDI1YTJkZTQ3N1wiLFwiMzguMlwiOlwiNDdiNmI2Y2NhOWQyYTBkNTdkZGI0OGZlNmMzMzBlNzdcIixcIjM4LjNcIjpcImM4NjQ4OTQxNzQ0ZGY5OWYxMWE2YzlkMGJkOTFmNDVhXCIsXCI0NC4xXCI6XCJjZDMwMzUyN2Q1NTlmYjMwZjQ4NTNlMDI1YTJkZTQ3N1wiLFwiNDQuMlwiOlwiOWU5NzYzMjA4NThkNjM0OTA3YWM0YjI5ZTRhMWQxMDdcIixcIjQ0LjNcIjpcImM4NjQ4OTQxNzQ0ZGY5OWYxMWE2YzlkMGJkOTFmNDVhXCJ9IiwiMmIwMTkyM2I5YWJiMmY3YjM1NjE2MDA4ZTQ5OGU5NzAiXQ==' \/>\n            <input type='hidden' class='gform_hidden' name='gform_target_page_number_5' id='gform_target_page_number_5' value='0' \/>\n            <input type='hidden' class='gform_hidden' name='gform_source_page_number_5' id='gform_source_page_number_5' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_5' id='gform_ajax_frame_5' title='Dieser iframe enth\u00e4lt die erforderliche Logik um Gravity Forms Formulare mit AJAX zu handhaben.'><\/iframe>\n\t\t                <script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 5, 'https:\/\/biobeach.gr\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_5').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_5');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_5').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_5').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_5').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_5').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_5').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_5').val();gformInitSpinner( 5, 'https:\/\/biobeach.gr\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [5, current_page]);window['gf_submitting_5'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}setTimeout(function(){jQuery('#gform_wrapper_5').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_5').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [5]);window['gf_submitting_5'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_5').text());}, 50);}else{jQuery('#gform_5').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger('gform_post_render', [5, current_page]);gform.utils.trigger({ event: 'gform\/postRender', native: false, data: { formId: 5, currentPage: current_page } });} );} );\n<\/script>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":14672,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/biobeach.gr\/de\/wp-json\/wp\/v2\/pages\/13687"}],"collection":[{"href":"https:\/\/biobeach.gr\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/biobeach.gr\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/biobeach.gr\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/biobeach.gr\/de\/wp-json\/wp\/v2\/comments?post=13687"}],"version-history":[{"count":3,"href":"https:\/\/biobeach.gr\/de\/wp-json\/wp\/v2\/pages\/13687\/revisions"}],"predecessor-version":[{"id":13695,"href":"https:\/\/biobeach.gr\/de\/wp-json\/wp\/v2\/pages\/13687\/revisions\/13695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biobeach.gr\/de\/wp-json\/wp\/v2\/media\/14672"}],"wp:attachment":[{"href":"https:\/\/biobeach.gr\/de\/wp-json\/wp\/v2\/media?parent=13687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}